{"id":72,"date":"2026-08-19T16:00:46","date_gmt":"2026-08-19T16:00:46","guid":{"rendered":"https:\/\/isabelle-bodiguel.fr\/index.php\/mentions\/"},"modified":"2026-08-20T07:19:43","modified_gmt":"2026-08-20T07:19:43","slug":"mentions","status":"publish","type":"page","link":"https:\/\/isabelle-bodiguel.fr\/index.php\/mentions\/","title":{"rendered":"Mentions"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"201\" height=\"200\" src=\"http:\/\/isabelle-bodiguel.fr\/wp-content\/uploads\/2026\/08\/pie-rose2.jpg\" alt=\"\" class=\"wp-image-174\" srcset=\"https:\/\/isabelle-bodiguel.fr\/wp-content\/uploads\/2026\/08\/pie-rose2.jpg 201w, https:\/\/isabelle-bodiguel.fr\/wp-content\/uploads\/2026\/08\/pie-rose2-150x150.jpg 150w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/figure>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\"><strong>1. \u00c9diteur du site<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Site \u00e9dit\u00e9 par Isabelle Bodiguel, 10 all\u00e9e de Crainquebille <br>37540 Saint-Cyr sur Loire<br>iguiffant@sfr.fr<br>SIRET : 447 630 013 00020<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">2. H\u00e9bergement<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">H\u00e9bergeur : OVH 2 rue Kellermann 59100 Roubaix<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">3. Propri\u00e9t\u00e9 intellectuelle<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Les textes, images, sculptures et contenus pr\u00e9sents sur ce site sont prot\u00e9g\u00e9s par le droit d\u2019auteur. Toute reproduction ou utilisation sans autorisation est interdite.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">4. Donn\u00e9es personnelles<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Les donn\u00e9es collect\u00e9es via le formulaire de contact ou les inscriptions aux cours\/stages sont utilis\u00e9es uniquement pour r\u00e9pondre aux demandes. Conform\u00e9ment au RGPD, vous pouvez exercer vos droits (acc\u00e8s, rectification, suppression) en \u00e9crivant \u00e0 : iguiffant@sfr.fr<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">5. Cookies<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Ce site peut utiliser des cookies pour am\u00e9liorer la navigation. Vous pouvez les refuser ou les param\u00e9trer dans votre navigateur.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">6. Responsabilit\u00e9<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">L\u2019\u00e9diteur ne peut garantir l\u2019exactitude permanente des informations et d\u00e9cline toute responsabilit\u00e9 en cas d\u2019erreur ou de dysfonctionnement du site.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. \u00c9diteur du site Site \u00e9dit\u00e9 par Isabelle Bodiguel, 10 all\u00e9e de Crainquebille 37540 Saint-Cyr sur Loireiguiffant@sfr.frSIRET : 447 630 013 00020 2. H\u00e9bergement H\u00e9bergeur : OVH 2 rue Kellermann 59100 Roubaix 3. Propri\u00e9t\u00e9 intellectuelle Les textes, images, sculptures et contenus pr\u00e9sents sur ce site sont prot\u00e9g\u00e9s par le droit d\u2019auteur. Toute reproduction ou utilisation [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-72","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/pages\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/comments?post=72"}],"version-history":[{"count":4,"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/pages\/72\/revisions"}],"predecessor-version":[{"id":175,"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/pages\/72\/revisions\/175"}],"wp:attachment":[{"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/media?parent=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}