{"id":25,"date":"2026-08-19T15:01:58","date_gmt":"2026-08-19T15:01:58","guid":{"rendered":"https:\/\/isabelle-bodiguel.fr\/index.php\/astuces\/"},"modified":"2026-08-22T15:22:26","modified_gmt":"2026-08-22T15:22:26","slug":"astuces","status":"publish","type":"page","link":"https:\/\/isabelle-bodiguel.fr\/index.php\/astuces\/","title":{"rendered":"Astuces"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"is-style-default has-x-large-font-size wp-block-paragraph\">Le vinaigre blanc, c&rsquo;est \u00e9patant !<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Le vinaigre est int\u00e9ressant dans la barbotine parce qu\u2019il <strong>renforce l\u2019adh\u00e9rence<\/strong> entre deux pi\u00e8ces d\u2019argile. <br>Son acidit\u00e9 agit directement sur la terre : elle <strong>neutralise les ions sodium<\/strong>, responsables d\u2019un effet d\u00e9floculant, et <strong>dissout tr\u00e8s l\u00e9g\u00e8rement la surface de l\u2019argile<\/strong>. R\u00e9sultat : la barbotine devient plus \u00ab accrocheuse \u00bb, plus stable, et cr\u00e9e une jonction beaucoup plus solide.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Cela signifie des assemblages plus fiables pour les zones d\u00e9licates  sans risque de d\u00e9collement au s\u00e9chage ou \u00e0 la cuisson. <br>Pratique ! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"is-style-text-subtitle is-style-text-subtitle--1 wp-block-paragraph\">Doucement, mais s\u00fbrement !<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Pour le <strong>s\u00e9chage des pi\u00e8ces en argile<\/strong>, le conseil simple mais essentiel : <strong>ma\u00eetriser la lenteur<\/strong>. C\u2019est elle qui \u00e9vite les fissures, les tensions internes et les d\u00e9collements sur les assemblages. <br><br>Plus l\u2019argile s\u00e8che doucement, plus elle reste stable. Un s\u00e9chage trop rapide cr\u00e9e des tensions et des fissures.<br><strong>Couvrir la pi\u00e8ce<\/strong> \u2014 Un sac plastique ou un tissu humide ralentit l\u2019\u00e9vaporation. <br><strong>Uniformiser les \u00e9paisseurs<\/strong> \u2014 Les zones fines s\u00e8chent plus vite que les zones \u00e9paisses : c\u2019est une source majeure de fissures.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"is-style-text-subtitle is-style-text-subtitle--2 wp-block-paragraph\">La Chamotte, l&rsquo;alli\u00e9 du sculpteur<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">La <strong>chamotte<\/strong> est pr\u00e9cieuse dans l\u2019argile parce qu\u2019elle <strong>stabilise la terre<\/strong>, <strong>r\u00e9duit les fissures<\/strong>, et <strong>renforce les sculptures<\/strong>, surtout les pi\u00e8ces volumineuses ou complexes .<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>En clair :<\/strong> ce sont des grains d\u2019argile d\u00e9j\u00e0 cuite, broy\u00e9e, qui jouent le r\u00f4le d\u2019un squelette interne. Ils emp\u00eachent l\u2019argile de trop se r\u00e9tracter, l\u2019aident \u00e0 s\u00e9cher plus r\u00e9guli\u00e8rement et lui donnent une tenue incomparable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le vinaigre blanc, c&rsquo;est \u00e9patant ! Le vinaigre est int\u00e9ressant dans la barbotine parce qu\u2019il renforce l\u2019adh\u00e9rence entre deux pi\u00e8ces d\u2019argile. Son acidit\u00e9 agit directement sur la terre : elle neutralise les ions sodium, responsables d\u2019un effet d\u00e9floculant, et dissout tr\u00e8s l\u00e9g\u00e8rement la surface de l\u2019argile. R\u00e9sultat : la barbotine devient plus \u00ab accrocheuse \u00bb, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":6,"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":341,"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/pages\/25\/revisions\/341"}],"wp:attachment":[{"href":"https:\/\/isabelle-bodiguel.fr\/index.php\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}